{"id":24007,"date":"2021-05-28T02:21:18","date_gmt":"2021-05-28T02:21:18","guid":{"rendered":"https:\/\/www2.visitmalta.com\/a\/gozo-and-comino\/"},"modified":"2021-05-28T04:30:36","modified_gmt":"2021-05-28T04:30:36","slug":"gozo-and-comino","status":"publish","type":"a","link":"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/","title":{"rendered":"Gozo&#032;&#038;&#032;Comino"},"content":{"rendered":"<div class=\"page-article__content\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-12 col-lg-8 offset-lg-2\">\n<h2 class=\"mb-5 text-center font-weight-bold\">                              Gozo&#032;&#038;&#032;Comino<\/h2>\n<div id=\"dvArticle\">      <span id=\"ctl00_ctl00_Body_PageContent_ContentControl_lblPageContent\"><\/p>\n<p>Alcuni tra i piu&#8217; affascinanti tesori al mondo aspettano solo di essere esplorati.<\/p>\n<p>Scopri le &#8220;Isole sorelle&#8221; di Gozo e Comino, facili da raggiungere e visitare, e scegli tra gli alloggi disponibili, come gli alberghi o i casali idilliaci. Raccogli informazioni riguardo le attivita&#8217; ed i luoghi da visitare. Per pianificare il tuo viaggio puoi rivolgerti ai centri di informazione turistica.<\/p>\n<p>Sia che tu voglia trascorrere l&#8217;intera vacanza a Gozo e Comino o fare qui una tappa durante il soggiorno a Malta, troverai luoghi speciali ed indimenticabili da esplorare.<\/p>\n<p>Luogo mitologico, Gozo e&#8217; considerata essere la famosa Isola di Calipso, cantata nell&#8217;Odissea di Omero. Un paradiso pieno di pace e circondato da acque mistiche. Chiese barocche e antiche pietre puntellano tutto il paesaggio. Gozo, con il suo territorio aspro, le sue spettacolari coste e alcuni tra i migliori siti di immersioni del Mediterraneo, attende solo di essere esplorata.<\/p>\n<p>E&#8217; possibile inoltre ammirare diversi siti storici, fortezze e panorami mozzafiato, cosi&#8217; come uno dei templi preistorici meglio conservati dell&#8217;arcipelago, \u0120gantija.<\/p>\n<p>Scopri Comino per la magia delle immersioni, il piacere di nuotare nelle sue limpide acque e godi di tutte le attivit&agrave; che il mare ha da offrire. <em>Blue Lagoon<\/em>, dalle acque turchesi e sicure, rendera&#8217; le giornate in barca memorabili. <\/p>\n<p>L&#8217;isola e&#8217; molto piccola ed ospita un unico hotel. Comino e&#8217; circondata dalle acque piu&#8217; trasparenti del Mediterraneo, una piscina naturale dove poter fare immersioni, snorkeling e attraccare con le barche per fare un bagno e rilassarsi. Durante l&#8217;inverno e&#8217; il luogo giusto per escursionisti e amanti della fotografia. Senza aree urbane e macchine, essa offre solo quiete e tranquillita&#8217;, lontano dallo smog e dal traffico.<\/p>\n<p>Per iniziare al meglio il tuo viaggio potrai rilevare la tua posizione utilizzando le nostre mappe interattive.<\/p>\n<p><div class='video-container'><\/div>\n<\/p>\n<p><a href=\"http:\/\/issuu.com\/visitmalta\/docs\/gozo_100momenti_it\/1\" target=\"_blank\" rel=\"noopener\">GOZO &#8211; 100 Momenti di Felicita&#8217;<\/a><\/p>\n<p><\/span>  <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"featured_media":0,"parent":0,"template":"","class_list":["post-24007","a","type-a","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gozo&#032;&#038;&#032;Comino - Visit Malta<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gozo&#032;&#038;&#032;Comino - Visit Malta\" \/>\n<meta property=\"og:description\" content=\"Gozo&#032;&#038;&#032;Comino Alcuni tra i piu&#8217; affascinanti tesori al mondo aspettano solo di essere esplorati. Scopri le &#8220;Isole sorelle&#8221; di Gozo e Comino, facili da raggiungere e visitare, e scegli tra gli alloggi disponibili, come gli alberghi o i casali idilliaci. Raccogli informazioni riguardo le attivita&#8217; ed i luoghi da visitare. Per pianificare il tuo viaggio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Malta\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-28T04:30:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/a\\\/gozo-and-comino\\\/\",\"url\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/a\\\/gozo-and-comino\\\/\",\"name\":\"Gozo&#032;&#038;&#032;Comino - Visit Malta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/#website\"},\"datePublished\":\"2021-05-28T02:21:18+00:00\",\"dateModified\":\"2021-05-28T04:30:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/a\\\/gozo-and-comino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/a\\\/gozo-and-comino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/a\\\/gozo-and-comino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gozo&#032;&#038;&#032;Comino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/\",\"name\":\"Visit Malta\",\"description\":\"The Official Tourism Site for Malta, Gozo and Comino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitmalta.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gozo&#032;&#038;&#032;Comino - Visit Malta","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Gozo&#032;&#038;&#032;Comino - Visit Malta","og_description":"Gozo&#032;&#038;&#032;Comino Alcuni tra i piu&#8217; affascinanti tesori al mondo aspettano solo di essere esplorati. Scopri le &#8220;Isole sorelle&#8221; di Gozo e Comino, facili da raggiungere e visitare, e scegli tra gli alloggi disponibili, come gli alberghi o i casali idilliaci. Raccogli informazioni riguardo le attivita&#8217; ed i luoghi da visitare. Per pianificare il tuo viaggio [&hellip;]","og_url":"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/","og_site_name":"Visit Malta","article_modified_time":"2021-05-28T04:30:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/","url":"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/","name":"Gozo&#032;&#038;&#032;Comino - Visit Malta","isPartOf":{"@id":"https:\/\/www.visitmalta.com\/it\/#website"},"datePublished":"2021-05-28T02:21:18+00:00","dateModified":"2021-05-28T04:30:36+00:00","breadcrumb":{"@id":"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitmalta.com\/it\/a\/gozo-and-comino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visitmalta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Gozo&#032;&#038;&#032;Comino"}]},{"@type":"WebSite","@id":"https:\/\/www.visitmalta.com\/it\/#website","url":"https:\/\/www.visitmalta.com\/it\/","name":"Visit Malta","description":"The Official Tourism Site for Malta, Gozo and Comino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitmalta.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.visitmalta.com\/it\/wp-json\/wp\/v2\/a\/24007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitmalta.com\/it\/wp-json\/wp\/v2\/a"}],"about":[{"href":"https:\/\/www.visitmalta.com\/it\/wp-json\/wp\/v2\/types\/a"}],"wp:attachment":[{"href":"https:\/\/www.visitmalta.com\/it\/wp-json\/wp\/v2\/media?parent=24007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}